{"id":569,"date":"2025-05-16T10:52:28","date_gmt":"2025-05-16T08:52:28","guid":{"rendered":"https:\/\/oopils.com\/home\/"},"modified":"2026-03-09T13:34:39","modified_gmt":"2026-03-09T12:34:39","slug":"home","status":"publish","type":"page","link":"https:\/\/oopils.com\/es\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"569\" class=\"elementor elementor-569 elementor-31\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b04a76d e-flex e-con-boxed e-con e-parent\" data-id=\"b04a76d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;position&quot;:&quot;absolute&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4a51a82 elementor-shape-rounded elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"4a51a82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-tiktok elementor-repeater-item-956bb76\" href=\"https:\/\/www.tiktok.com\/@oopils\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Tiktok<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-tiktok\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M448,209.91a210.06,210.06,0,0,1-122.77-39.25V349.38A162.55,162.55,0,1,1,185,188.31V278.2a74.62,74.62,0,1,0,52.23,71.18V0l88,0a121.18,121.18,0,0,0,1.86,22.17h0A122.18,122.18,0,0,0,381,102.39a121.43,121.43,0,0,0,67,20.14Z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-86edaf5\" href=\"https:\/\/www.instagram.com\/oopils_official\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-599c247 elementor-widget elementor-widget-wpml-language-switcher\" data-id=\"599c247\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpml-language-switcher.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpml-elementor-ls\">\n<div role=\"navigation\" aria-label=\"Selector de idioma\" class=\"wpml-ls-statics-shortcode_actions wpml-ls wpml-ls-legacy-list-horizontal\">\n\t<ul><li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-en wpml-ls-first-item wpml-ls-item-legacy-list-horizontal\">\n\t\t\t\t<a href=\"https:\/\/oopils.com\/\" hreflang=\"en\" lang=\"en\" class=\"wpml-ls-link\" aria-label=\"Cambiar a EN\" title=\"Cambiar a EN\">\n\t\t\t\t\t<span class=\"wpml-ls-native\">EN<\/span><\/a>\n\t\t\t<\/li><li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-es wpml-ls-current-language wpml-ls-last-item wpml-ls-item-legacy-list-horizontal\">\n\t\t\t\t<a href=\"https:\/\/oopils.com\/es\/\" hreflang=\"es\" lang=\"es\" class=\"wpml-ls-link\" aria-current=\"page\" aria-label=\"Cambiar a ES\" title=\"Cambiar a ES\">\n\t\t\t\t\t<span class=\"wpml-ls-native\">ES<\/span><\/a>\n\t\t\t<\/li><\/ul>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-593e7b3 e-flex e-con-boxed e-con e-parent\" data-id=\"593e7b3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-af59817 e-con-full e-flex e-con e-child\" data-id=\"af59817\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0051b70 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"0051b70\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f2bce7f elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"f2bce7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"397\" src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/spr_Logo_Oopils.png\" class=\"attachment-large size-large wp-image-513\" alt=\"\" srcset=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/spr_Logo_Oopils.png 918w, https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/spr_Logo_Oopils-300x149.png 300w, https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/spr_Logo_Oopils-768x381.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6071772 elementor-widget elementor-widget-heading\" data-id=\"6071772\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Haz historia.\u2028<br>\nGira, conecta\u2026\u2028<br>\ny viaja en el tiempo.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd03069 elementor-widget__width-initial elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"dd03069\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Descubre el juego de puzzle que te reta a pensar en formas, colores y estrategia. Los Oopils han llegado para divertirte y contarte la historia real (o casi).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0399437 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"0399437\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f5c91a5 boton-descarga elementor-widget elementor-widget-image\" data-id=\"f5c91a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.potioncode.oopils\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"228\" src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/google-play.png\" class=\"attachment-large size-large wp-image-518\" alt=\"\" srcset=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/google-play.png 768w, https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/google-play-300x89.png 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d652d24 elementor-widget elementor-widget-image\" data-id=\"d652d24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apps.apple.com\/es\/app\/oopils\/id6755389544\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"661\" height=\"228\" src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/app-store.png\" class=\"attachment-large size-large wp-image-519\" alt=\"\" srcset=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/app-store.png 661w, https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/app-store-300x103.png 300w\" sizes=\"(max-width: 661px) 100vw, 661px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-92da42b e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"92da42b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e1e402 flota elementor-invisible elementor-widget elementor-widget-image\" data-id=\"0e1e402\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"246\" src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/Ship-300x246.png\" class=\"attachment-medium size-medium wp-image-520\" alt=\"\" srcset=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/Ship-300x246.png 300w, https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/Ship.png 435w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29669f2 elementor-widget elementor-widget-image\" data-id=\"29669f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NDg3LCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"487\" src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/vide-game-poster.jpg\" class=\"attachment-large size-large wp-image-523\" alt=\"\" srcset=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/vide-game-poster.jpg 740w, https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/vide-game-poster-300x197.jpg 300w\" sizes=\"(max-width: 740px) 100vw, 740px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e85858b elementor-widget__width-initial elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"e85858b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Descubre el juego de puzzle que te reta a pensar en formas, colores y estrategia. Los Oopils han llegado para divertirte y contarte la historia real (o casi).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5688bd2 e-con-full elementor-hidden-desktop elementor-hidden-tablet e-flex e-con e-child\" data-id=\"5688bd2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b51fdd8 boton-descarga elementor-widget elementor-widget-image\" data-id=\"b51fdd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.potioncode.oopils\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"238\" src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/06\/Google_Play_Store_badge_EN.svg_-1024x304.png\" class=\"attachment-large size-large wp-image-565\" alt=\"\" srcset=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/06\/Google_Play_Store_badge_EN.svg_-1024x304.png 1024w, https:\/\/oopils.com\/wp-content\/uploads\/2025\/06\/Google_Play_Store_badge_EN.svg_-300x89.png 300w, https:\/\/oopils.com\/wp-content\/uploads\/2025\/06\/Google_Play_Store_badge_EN.svg_-768x228.png 768w, https:\/\/oopils.com\/wp-content\/uploads\/2025\/06\/Google_Play_Store_badge_EN.svg_.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-981c78f elementor-widget elementor-widget-image\" data-id=\"981c78f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apps.apple.com\/es\/app\/oopils\/id6755389544\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"238\" src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/06\/Download_on_the_App_Store_Badge.svg_-1024x304.png\" class=\"attachment-large size-large wp-image-562\" alt=\"\" srcset=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/06\/Download_on_the_App_Store_Badge.svg_-1024x304.png 1024w, https:\/\/oopils.com\/wp-content\/uploads\/2025\/06\/Download_on_the_App_Store_Badge.svg_-300x89.png 300w, https:\/\/oopils.com\/wp-content\/uploads\/2025\/06\/Download_on_the_App_Store_Badge.svg_-768x228.png 768w, https:\/\/oopils.com\/wp-content\/uploads\/2025\/06\/Download_on_the_App_Store_Badge.svg_-1536x455.png 1536w, https:\/\/oopils.com\/wp-content\/uploads\/2025\/06\/Download_on_the_App_Store_Badge.svg_-2048x607.png 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cfcda2f e-con-full e-flex e-con e-child\" data-id=\"cfcda2f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;position&quot;:&quot;absolute&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d3f81ee elementor-widget elementor-widget-heading\" data-id=\"d3f81ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"#como-se-juega\">\u00bfC\u00f3mo se juega?\n<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0be4fbd e-transform flechas-ico elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"0be4fbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:9,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#como-se-juega\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 256.3L7 120.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0L313 86.3c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.4 9.5-24.6 9.5-34 .1zm34 192l136-136c9.4-9.4 9.4-24.6 0-33.9l-22.6-22.6c-9.4-9.4-24.6-9.4-33.9 0L160 352.1l-96.4-96.4c-9.4-9.4-24.6-9.4-33.9 0L7 278.3c-9.4 9.4-9.4 24.6 0 33.9l136 136c9.4 9.5 24.6 9.5 34 .1z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e3a00b8 e-flex e-con-boxed e-con e-parent\" data-id=\"e3a00b8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c9e7602 e-con-full e-flex e-con e-child\" data-id=\"c9e7602\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1f5f2a7 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"1f5f2a7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-03c9df7 elementor-widget elementor-widget-menu-anchor\" data-id=\"03c9df7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"como-se-juega\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-205afe7 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"205afe7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"207\" height=\"300\" src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/espada-207x300.png\" class=\"attachment-medium size-medium wp-image-524\" alt=\"\" srcset=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/espada-207x300.png 207w, https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/espada.png 277w\" sizes=\"(max-width: 207px) 100vw, 207px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d222b7 carrusel-movil  elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"9d222b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/oopils-juego-1.png\" alt=\"oopils-juego-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/oopils-juego-2.png\" alt=\"oopils-juego-2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/oopils-juego-3.png\" alt=\"oopils-juego-3\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/oopils-juego-4.png\" alt=\"oopils-juego-4\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/oopils-juego-5.png\" alt=\"oopils-juego-5\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a5ba0c4 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"a5ba0c4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-82cd05d elementor-widget elementor-widget-spacer\" data-id=\"82cd05d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2530dc elementor-widget elementor-widget-heading\" data-id=\"c2530dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Juntar colores\u2026\u2028<br>\nEso es demasiado f\u00e1cil<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6315b2 elementor-widget elementor-widget-heading\" data-id=\"d6315b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Desliza, piensa, gira y resuelve el puzzle m\u00e1s ingenioso del momento.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e609abe elementor-widget elementor-widget-text-editor\" data-id=\"e609abe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">En Oopils no basta con alinear tres colores. Aqu\u00ed deber\u00e1s formar figuras concretas con los personajes, \u00a1y si no puedes\u2026 gira el tablero!<\/p><p class=\"p1\">Cada casilla tiene colores en sus bordes. Si giras y haces coincidir los colores, los Oopils se mover\u00e1n de casilla, desbloqueando nuevas posiciones.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56f162c flota elementor-widget elementor-widget-image\" data-id=\"56f162c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.7,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"415\" height=\"247\" src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/butterfly.png\" class=\"attachment-large size-large wp-image-527\" alt=\"\" srcset=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/butterfly.png 415w, https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/butterfly-300x179.png 300w\" sizes=\"(max-width: 415px) 100vw, 415px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8f1802f e-con-full e-flex e-con e-child\" data-id=\"8f1802f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;position&quot;:&quot;absolute&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f130a2 elementor-widget elementor-widget-heading\" data-id=\"5f130a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"#que-lo-hace-diferente\">\u00bfQu\u00e9 lo hace diferente?<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-601ce11 e-transform flechas-ico elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"601ce11\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:9,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#que-lo-hace-diferente\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 256.3L7 120.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0L313 86.3c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.4 9.5-24.6 9.5-34 .1zm34 192l136-136c9.4-9.4 9.4-24.6 0-33.9l-22.6-22.6c-9.4-9.4-24.6-9.4-33.9 0L160 352.1l-96.4-96.4c-9.4-9.4-24.6-9.4-33.9 0L7 278.3c-9.4 9.4-9.4 24.6 0 33.9l136 136c9.4 9.5 24.6 9.5 34 .1z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eb12c78 e-flex e-con-boxed e-con e-parent\" data-id=\"eb12c78\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c9cd01b elementor-widget elementor-widget-menu-anchor\" data-id=\"c9cd01b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"que-lo-hace-diferente\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93cd7be separador e-transform elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"93cd7be\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:9,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8c458b6 e-flex e-con-boxed e-con e-parent\" data-id=\"8c458b6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8dba20c e-con-full e-flex e-con e-child\" data-id=\"8dba20c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d296dfa e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"d296dfa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d722630 elementor-widget elementor-widget-heading\" data-id=\"d722630\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un giro de cabeza\u2028<br>\n(y de tablero).<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-090d96b elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"090d96b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Oopils es \u00fanico porque combina la l\u00f3gica de un puzzle con la estrategia de movimiento.<\/p><p class=\"p1\">Gira casillas, conecta colores y busca la figura objetivo para avanzar. Cada partida es un desaf\u00edo visual y mental.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fc9c2d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7fc9c2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Retos crecientes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mec\u00e1nicas innovadoras<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Jugabilidad atractiva que te invitara a seguir explorando sin estr\u00e9s<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ed693dc e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"ed693dc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fcab278 flota elementor-widget elementor-widget-image\" data-id=\"fcab278\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.7,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"526\" height=\"432\" src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/Parchis.png\" class=\"attachment-full size-full wp-image-528\" alt=\"\" srcset=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/Parchis.png 526w, https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/Parchis-300x246.png 300w\" sizes=\"(max-width: 526px) 100vw, 526px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2055e65 e-con-full e-flex e-con e-child\" data-id=\"2055e65\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;position&quot;:&quot;absolute&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43964b2 elementor-widget elementor-widget-heading\" data-id=\"43964b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"#viaja-con-oopils\">Viaja por el tiempo con Oopils<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d6b367 e-transform flechas-ico elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"5d6b367\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:9,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#viaja-con-oopils\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 256.3L7 120.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0L313 86.3c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.4 9.5-24.6 9.5-34 .1zm34 192l136-136c9.4-9.4 9.4-24.6 0-33.9l-22.6-22.6c-9.4-9.4-24.6-9.4-33.9 0L160 352.1l-96.4-96.4c-9.4-9.4-24.6-9.4-33.9 0L7 278.3c-9.4 9.4-9.4 24.6 0 33.9l136 136c9.4 9.5 24.6 9.5 34 .1z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d2b96df e-flex e-con-boxed e-con e-parent\" data-id=\"d2b96df\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7abbb92 elementor-widget elementor-widget-menu-anchor\" data-id=\"7abbb92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"viaja-con-oopils\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee3e297 flota elementor-widget elementor-widget-image\" data-id=\"ee3e297\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"148\" height=\"148\" src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/oopils_Einstein.png\" class=\"attachment-large size-large wp-image-529\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-541f06f separador elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"541f06f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2211d11 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2211d11\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Los Oopils siempre estuvieron ah\u00ed...<br>\ny nadie se enter\u00f3.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60939d3 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"60939d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">\u00bfSab\u00edas que los Oopils ayudaron a la humanidad a descubrir el fuego? \u00bfO que guiaron a los ingenieros para construir la Gran Muralla China?<br \/>Cada nivel desbloquea un momento \u00e9pico de la historia\u2026 con una vi\u00f1eta de c\u00f3mic divertida y un escenario totalmente nuevo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-099a4f6 e-con-full e-flex e-con e-parent\" data-id=\"099a4f6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3c123cc carrusel-fotos elementor-invisible elementor-widget elementor-widget-image-carousel\" data-id=\"3c123cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;5&quot;,&quot;slides_to_show_tablet&quot;:&quot;3&quot;,&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 19\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3c123cc\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTMwLCJ1cmwiOiJodHRwczpcL1wvb29waWxzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDVcL2JlYXRsZXMuanBnIiwic2xpZGVzaG93IjoiM2MxMjNjYyJ9\" href=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/beatles.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/beatles.jpg\" alt=\"beatles\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 19\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3c123cc\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTMxLCJ1cmwiOiJodHRwczpcL1wvb29waWxzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDVcL2NlcnZhbnRlcy5qcGciLCJzbGlkZXNob3ciOiIzYzEyM2NjIn0%3D\" href=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/cervantes.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/cervantes.jpg\" alt=\"cervantes\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 19\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3c123cc\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTMyLCJ1cmwiOiJodHRwczpcL1wvb29waWxzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDVcL2NoYW5lbC5qcGciLCJzbGlkZXNob3ciOiIzYzEyM2NjIn0%3D\" href=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/chanel.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/chanel.jpg\" alt=\"chanel\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 19\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3c123cc\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTMzLCJ1cmwiOiJodHRwczpcL1wvb29waWxzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDVcL2NoaW5hLmpwZyIsInNsaWRlc2hvdyI6IjNjMTIzY2MifQ%3D%3D\" href=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/china.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/china.jpg\" alt=\"china\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 19\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3c123cc\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTM0LCJ1cmwiOiJodHRwczpcL1wvb29waWxzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDVcL2N1cmllLmpwZyIsInNsaWRlc2hvdyI6IjNjMTIzY2MifQ%3D%3D\" href=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/curie.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/curie.jpg\" alt=\"curie\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 19\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3c123cc\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTM1LCJ1cmwiOiJodHRwczpcL1wvb29waWxzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDVcL2VkaXNvbi5qcGciLCJzbGlkZXNob3ciOiIzYzEyM2NjIn0%3D\" href=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/edison.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/edison.jpg\" alt=\"edison\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 19\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3c123cc\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTM2LCJ1cmwiOiJodHRwczpcL1wvb29waWxzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDVcL2VpbnN0ZWluLmpwZyIsInNsaWRlc2hvdyI6IjNjMTIzY2MifQ%3D%3D\" href=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/einstein.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/einstein.jpg\" alt=\"einstein\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 19\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3c123cc\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTM3LCJ1cmwiOiJodHRwczpcL1wvb29waWxzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDVcL2dhbGlsZW8uanBnIiwic2xpZGVzaG93IjoiM2MxMjNjYyJ9\" href=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/galileo.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/galileo.jpg\" alt=\"galileo\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 de 19\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3c123cc\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTM4LCJ1cmwiOiJodHRwczpcL1wvb29waWxzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDVcL2pvcmRhbi5qcGciLCJzbGlkZXNob3ciOiIzYzEyM2NjIn0%3D\" href=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/jordan.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/jordan.jpg\" alt=\"jordan\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 de 19\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3c123cc\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTM5LCJ1cmwiOiJodHRwczpcL1wvb29waWxzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDVcL21heWFzLmpwZyIsInNsaWRlc2hvdyI6IjNjMTIzY2MifQ%3D%3D\" href=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/mayas.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/mayas.jpg\" alt=\"mayas\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 de 19\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3c123cc\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTQwLCJ1cmwiOiJodHRwczpcL1wvb29waWxzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDVcL21vb25sYW5kaW5nLmpwZyIsInNsaWRlc2hvdyI6IjNjMTIzY2MifQ%3D%3D\" href=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/moonlanding.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/moonlanding.jpg\" alt=\"moonlanding\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 de 19\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3c123cc\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTQxLCJ1cmwiOiJodHRwczpcL1wvb29waWxzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDVcL25ld3Rvbi5qcGciLCJzbGlkZXNob3ciOiIzYzEyM2NjIn0%3D\" href=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/newton.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/newton.jpg\" alt=\"newton\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 de 19\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3c123cc\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTQyLCJ1cmwiOiJodHRwczpcL1wvb29waWxzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDVcL29seW1waWNzLmpwZyIsInNsaWRlc2hvdyI6IjNjMTIzY2MifQ%3D%3D\" href=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/olympics.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/olympics.jpg\" alt=\"olympics\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 de 19\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3c123cc\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTQzLCJ1cmwiOiJodHRwczpcL1wvb29waWxzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDVcL29vcGlsLmpwZyIsInNsaWRlc2hvdyI6IjNjMTIzY2MifQ%3D%3D\" href=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/oopil.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/oopil.jpg\" alt=\"oopil\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 de 19\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3c123cc\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTQ0LCJ1cmwiOiJodHRwczpcL1wvb29waWxzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDVcL3BpcmFtaWRlcy5qcGciLCJzbGlkZXNob3ciOiIzYzEyM2NjIn0%3D\" href=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/piramides.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/piramides.jpg\" alt=\"piramides\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 de 19\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3c123cc\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTQ1LCJ1cmwiOiJodHRwczpcL1wvb29waWxzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDVcL3BpcmF0YXMuanBnIiwic2xpZGVzaG93IjoiM2MxMjNjYyJ9\" href=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/piratas.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/piratas.jpg\" alt=\"piratas\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 de 19\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3c123cc\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTQ2LCJ1cmwiOiJodHRwczpcL1wvb29waWxzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDVcL3N0b25laGVuZ2UuanBnIiwic2xpZGVzaG93IjoiM2MxMjNjYyJ9\" href=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/stonehenge.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/stonehenge.jpg\" alt=\"stonehenge\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 de 19\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3c123cc\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTQ3LCJ1cmwiOiJodHRwczpcL1wvb29waWxzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDVcL3ZpbmNpLmpwZyIsInNsaWRlc2hvdyI6IjNjMTIzY2MifQ%3D%3D\" href=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/vinci.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/vinci.jpg\" alt=\"vinci\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 de 19\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3c123cc\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTQ4LCJ1cmwiOiJodHRwczpcL1wvb29waWxzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDVcL3doZWVsLmpwZyIsInNsaWRlc2hvdyI6IjNjMTIzY2MifQ%3D%3D\" href=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/wheel.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/wheel.jpg\" alt=\"wheel\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d47d89 e-flex e-con-boxed e-con e-parent\" data-id=\"3d47d89\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a66247c elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"a66247c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Desde nuestros ancestros cavern\u00edcolas hasta el Renacimiento, <br \/>los Oopils te llevar\u00e1n en un viaje tan educativo como entretenido y divertido.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-697d3ac e-flex e-con-boxed e-con e-parent\" data-id=\"697d3ac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-820b2eb flota elementor-invisible elementor-widget elementor-widget-image\" data-id=\"820b2eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"569\" height=\"305\" src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/oopil-portal-b.png\" class=\"attachment-large size-large wp-image-549\" alt=\"\" srcset=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/oopil-portal-b.png 569w, https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/oopil-portal-b-300x161.png 300w\" sizes=\"(max-width: 569px) 100vw, 569px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f833f41 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"f833f41\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Tus Oopils te esperan<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3da5459 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"3da5459\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">\u00danete a una comunidad de jugadores que piensan diferente.<br \/>Descarga Oopils y vive la historia desde otro punto de vista\u2026 m\u00e1s colorido.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e5696fa e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"e5696fa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7bbfb48 boton-descarga elementor-widget elementor-widget-image\" data-id=\"7bbfb48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.potioncode.oopils\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"228\" src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/google-play.png\" class=\"attachment-large size-large wp-image-518\" alt=\"\" srcset=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/google-play.png 768w, https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/google-play-300x89.png 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af0d0c6 elementor-widget elementor-widget-image\" data-id=\"af0d0c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apps.apple.com\/es\/app\/oopils\/id6755389544\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"661\" height=\"228\" src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/app-store.png\" class=\"attachment-large size-large wp-image-519\" alt=\"\" srcset=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/app-store.png 661w, https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/app-store-300x103.png 300w\" sizes=\"(max-width: 661px) 100vw, 661px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8162e92 flota elementor-invisible elementor-widget elementor-widget-image\" data-id=\"8162e92\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"569\" height=\"305\" src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/oopil-portal.png\" class=\"attachment-large size-large wp-image-550\" alt=\"\" srcset=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/oopil-portal.png 569w, https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/oopil-portal-300x161.png 300w\" sizes=\"(max-width: 569px) 100vw, 569px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-68145b6 e-flex e-con-boxed e-con e-parent\" data-id=\"68145b6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ec6db1d e-con-full e-flex e-con e-child\" data-id=\"ec6db1d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c71b308 elementor-widget elementor-widget-heading\" data-id=\"c71b308\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Oopils, un juego de Potion Code S.L.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c9b025c e-con-full e-flex e-con e-child\" data-id=\"c9b025c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-455fb69 elementor-widget elementor-widget-image\" data-id=\"455fb69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/favicon_2-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-515\" alt=\"\" srcset=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/favicon_2-150x150.png 150w, https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/favicon_2-300x300.png 300w, https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/favicon_2.png 512w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-32c37b7 e-con-full e-flex e-con e-child\" data-id=\"32c37b7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-867d59e elementor-icon-list--layout-inline elementor-align-end elementor-tablet-align-center elementor-mobile-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"867d59e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/oopils.com\/es\/aviso-legal\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aviso legal<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/oopils.com\/es\/politica-de-privacidad\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pol\u00edtica de privacidad<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/oopils.com\/es\/politica-de-cookies\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pol\u00edtica de cookies<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/oopils.com\/es\/ayuda\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Soporte<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Tiktok Instagram EN ES Haz historia.\u2028 Gira, conecta\u2026\u2028 y viaja en el tiempo. Descubre el juego de puzzle que te reta a pensar en formas, colores y estrategia. Los Oopils han llegado para divertirte y contarte la historia real (o casi). Descubre el juego de puzzle que te reta a pensar en formas, colores y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":716,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-569","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home - Oopils<\/title>\n<meta name=\"description\" content=\"Descubre el juego de puzzle que te reta a pensar en formas, colores y estrategia. Los Oopils han llegado para divertirte y contarte la historia real (o casi).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oopils.com\/es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home - Oopils\" \/>\n<meta property=\"og:description\" content=\"Descubre el juego de puzzle que te reta a pensar en formas, colores y estrategia. Los Oopils han llegado para divertirte y contarte la historia real (o casi).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oopils.com\/es\/\" \/>\n<meta property=\"og:site_name\" content=\"Oopils\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-09T12:34:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/oopils.com\/wp-content\/uploads\/2025\/06\/potion.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"635\" \/>\n\t<meta property=\"og:image:height\" content=\"635\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/oopils.com\\\/es\\\/\",\"url\":\"https:\\\/\\\/oopils.com\\\/es\\\/\",\"name\":\"Home - Oopils\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oopils.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/oopils.com\\\/es\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/oopils.com\\\/es\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/oopils.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/potion.jpeg\",\"datePublished\":\"2025-05-16T08:52:28+00:00\",\"dateModified\":\"2026-03-09T12:34:39+00:00\",\"description\":\"Descubre el juego de puzzle que te reta a pensar en formas, colores y estrategia. Los Oopils han llegado para divertirte y contarte la historia real (o casi).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oopils.com\\\/es\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/oopils.com\\\/es\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/oopils.com\\\/es\\\/#primaryimage\",\"url\":\"https:\\\/\\\/oopils.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/potion.jpeg\",\"contentUrl\":\"https:\\\/\\\/oopils.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/potion.jpeg\",\"width\":635,\"height\":635,\"caption\":\"oopils the game\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oopils.com\\\/es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/oopils.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oopils.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/oopils.com\\\/es\\\/\",\"name\":\"Oopils\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/oopils.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oopils.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oopils.com\\\/es\\\/#organization\",\"name\":\"Oopils\",\"alternateName\":\"Oopils\",\"url\":\"https:\\\/\\\/oopils.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/oopils.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/oopils.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/spr_Logo_Oopils.png\",\"contentUrl\":\"https:\\\/\\\/oopils.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/spr_Logo_Oopils.png\",\"width\":918,\"height\":455,\"caption\":\"Oopils\"},\"image\":{\"@id\":\"https:\\\/\\\/oopils.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home - Oopils","description":"Descubre el juego de puzzle que te reta a pensar en formas, colores y estrategia. Los Oopils han llegado para divertirte y contarte la historia real (o casi).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oopils.com\/es\/","og_locale":"es_ES","og_type":"article","og_title":"Home - Oopils","og_description":"Descubre el juego de puzzle que te reta a pensar en formas, colores y estrategia. Los Oopils han llegado para divertirte y contarte la historia real (o casi).","og_url":"https:\/\/oopils.com\/es\/","og_site_name":"Oopils","article_modified_time":"2026-03-09T12:34:39+00:00","og_image":[{"width":635,"height":635,"url":"https:\/\/oopils.com\/wp-content\/uploads\/2025\/06\/potion.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/oopils.com\/es\/","url":"https:\/\/oopils.com\/es\/","name":"Home - Oopils","isPartOf":{"@id":"https:\/\/oopils.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/oopils.com\/es\/#primaryimage"},"image":{"@id":"https:\/\/oopils.com\/es\/#primaryimage"},"thumbnailUrl":"https:\/\/oopils.com\/wp-content\/uploads\/2025\/06\/potion.jpeg","datePublished":"2025-05-16T08:52:28+00:00","dateModified":"2026-03-09T12:34:39+00:00","description":"Descubre el juego de puzzle que te reta a pensar en formas, colores y estrategia. Los Oopils han llegado para divertirte y contarte la historia real (o casi).","breadcrumb":{"@id":"https:\/\/oopils.com\/es\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oopils.com\/es\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/oopils.com\/es\/#primaryimage","url":"https:\/\/oopils.com\/wp-content\/uploads\/2025\/06\/potion.jpeg","contentUrl":"https:\/\/oopils.com\/wp-content\/uploads\/2025\/06\/potion.jpeg","width":635,"height":635,"caption":"oopils the game"},{"@type":"BreadcrumbList","@id":"https:\/\/oopils.com\/es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/oopils.com\/es\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/oopils.com\/es\/#website","url":"https:\/\/oopils.com\/es\/","name":"Oopils","description":"","publisher":{"@id":"https:\/\/oopils.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oopils.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/oopils.com\/es\/#organization","name":"Oopils","alternateName":"Oopils","url":"https:\/\/oopils.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/oopils.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/spr_Logo_Oopils.png","contentUrl":"https:\/\/oopils.com\/wp-content\/uploads\/2025\/05\/spr_Logo_Oopils.png","width":918,"height":455,"caption":"Oopils"},"image":{"@id":"https:\/\/oopils.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/oopils.com\/es\/wp-json\/wp\/v2\/pages\/569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oopils.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oopils.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oopils.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oopils.com\/es\/wp-json\/wp\/v2\/comments?post=569"}],"version-history":[{"count":108,"href":"https:\/\/oopils.com\/es\/wp-json\/wp\/v2\/pages\/569\/revisions"}],"predecessor-version":[{"id":992,"href":"https:\/\/oopils.com\/es\/wp-json\/wp\/v2\/pages\/569\/revisions\/992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oopils.com\/es\/wp-json\/wp\/v2\/media\/716"}],"wp:attachment":[{"href":"https:\/\/oopils.com\/es\/wp-json\/wp\/v2\/media?parent=569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}